{"id":2292,"date":"2024-07-19T16:49:33","date_gmt":"2024-07-19T11:19:33","guid":{"rendered":"https:\/\/azrahomedecor.com\/?page_id=2292"},"modified":"2024-08-02T16:46:15","modified_gmt":"2024-08-02T11:16:15","slug":"home-azra-home-decor","status":"publish","type":"page","link":"https:\/\/azrahomedecor.com\/","title":{"rendered":"Home Azra home Decor"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2292\" class=\"elementor elementor-2292\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a800c9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9a800c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef5bf1a\" data-id=\"ef5bf1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f83441f elementor--h-position-left elementor--v-position-bottom elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"f83441f\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-5abf8b8 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Discover the Art of Handcrafted Elegance<\/div><div class=\"elementor-slide-description\">Handmade Masterpieces for Every Corner of Your Home<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-69ca0f9 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Hand Tufted: Timeless Craftsmanship<\/div><div class=\"elementor-slide-description\">Crafted with precision and care, our hand-tufted carpets showcase exquisite detail and durability.\n\n\n<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-0c09f23 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Hand Dyeing: Crafting Vibrant Textures<\/div><div class=\"elementor-slide-description\">Expertly hand-dyed for vibrant textures and unique patterns.\n\n\n\n\n\n\n<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97ff1ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97ff1ec\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40c2b3d\" data-id=\"40c2b3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8cf80e elementor-widget elementor-widget-heading\" data-id=\"e8cf80e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Authentic Rug Crafting Techniques<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3020af2 elementor-widget elementor-widget-text-editor\" data-id=\"3020af2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Experience the Elegance of Hand-Tufted, Hand-Knotted, Hand-Loomed, and Handwoven Techniques<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a15eb8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0a15eb8\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34447e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34447e4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-935deb5\" data-id=\"935deb5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55e63ab elementor-widget elementor-widget-image\" data-id=\"55e63ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/9-724x1024.jpg\" class=\"attachment-large size-large wp-image-2368\" alt=\"Hand-Tufted Creations for Timeless Elegance\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/9-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/9-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/9-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/9-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/9-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/9.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aa4f0e elementor-widget elementor-widget-heading\" data-id=\"2aa4f0e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hand Tufted <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ab0439f\" data-id=\"ab0439f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-881ff71 elementor-widget elementor-widget-image\" data-id=\"881ff71\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/7-724x1024.jpg\" class=\"attachment-large size-large wp-image-2366\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/7-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/7-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/7-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/7-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/7-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/7.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75dced9 elementor-widget elementor-widget-heading\" data-id=\"75dced9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hand Knotted<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a8be143\" data-id=\"a8be143\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd886b4 elementor-widget elementor-widget-image\" data-id=\"cd886b4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/8-724x1024.jpg\" class=\"attachment-large size-large wp-image-2367\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/8-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/8-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/8-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/8-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/8-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/8.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d226d6 elementor-widget elementor-widget-heading\" data-id=\"0d226d6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hand LOOM<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7f78f15\" data-id=\"7f78f15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83d64d1 elementor-widget elementor-widget-image\" data-id=\"83d64d1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/10-724x1024.jpg\" class=\"attachment-large size-large wp-image-2369\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/10-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/10-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/10-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/10-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/10-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/10.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7c5e39 elementor-widget elementor-widget-heading\" data-id=\"d7c5e39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hand WOVEN <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cee4ed6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cee4ed6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31ab98d\" data-id=\"31ab98d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77a36a9 elementor-widget elementor-widget-heading\" data-id=\"77a36a9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AZRA HOME DECOR<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-851a67d elementor-widget elementor-widget-text-editor\" data-id=\"851a67d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Connecting unparalleled craftsmanship, elevated designs, and exceptional experiences through ethical and sustainable business practices.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad84f59 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad84f59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b4c3b9d\" data-id=\"b4c3b9d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abc93ee elementor-widget elementor-widget-heading\" data-id=\"abc93ee\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sculpted &amp; Soft<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-673fe12 elementor-widget elementor-widget-text-editor\" data-id=\"673fe12\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hp-trends__callout-title\"><div class=\"hp-trends__callout_text\"><p>Textural pile offers high-low dimension that adds contemporary elegance to any space.<\/p><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57dc961 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"57dc961\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/azrahomedecor.com\/index.php\/products-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">kNOW mORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-48b01e2\" data-id=\"48b01e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07f635f elementor-widget elementor-widget-image\" data-id=\"07f635f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/Texture_HP_Block_-768x1024.jpeg\" class=\"attachment-large size-large wp-image-2325\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/Texture_HP_Block_-768x1024.jpeg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/Texture_HP_Block_-225x300.jpeg 225w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/Texture_HP_Block_.jpeg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e5e9841\" data-id=\"e5e9841\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57aed4a elementor-widget elementor-widget-image\" data-id=\"57aed4a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/soft-sculpted-feature-2-jun14-1024x768.webp\" class=\"attachment-large size-large wp-image-2326\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/soft-sculpted-feature-2-jun14-1024x768.webp 1024w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/soft-sculpted-feature-2-jun14-300x225.webp 300w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/soft-sculpted-feature-2-jun14-768x576.webp 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/soft-sculpted-feature-2-jun14.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee765ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee765ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9b4bf1a\" data-id=\"9b4bf1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-faf307d elementor-widget elementor-widget-image\" data-id=\"faf307d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/fine-fibers-feature2-april03-768x1024.webp\" class=\"attachment-large size-large wp-image-2339\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/fine-fibers-feature2-april03-768x1024.webp 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/fine-fibers-feature2-april03-225x300.webp 225w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/fine-fibers-feature2-april03.webp 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8f8ddbd\" data-id=\"8f8ddbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12bb16c elementor-widget elementor-widget-image\" data-id=\"12bb16c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/fine-fibers-feature-1-april03-1-1024x768.webp\" class=\"attachment-large size-large wp-image-2341\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/fine-fibers-feature-1-april03-1-1024x768.webp 1024w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/fine-fibers-feature-1-april03-1-300x225.webp 300w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/fine-fibers-feature-1-april03-1-768x576.webp 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/fine-fibers-feature-1-april03-1.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-36b6fad\" data-id=\"36b6fad\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f424d65 elementor-widget elementor-widget-heading\" data-id=\"f424d65\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fine Fibers<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c050320 elementor-widget elementor-widget-text-editor\" data-id=\"c050320\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"hp-trends__callout-title\"><div class=\"hp-trends__callout_text\"><div class=\"hp-trends__callout-title\"><div class=\"hp-trends__callout_text\"><p>Silk. Mongolian Cashmere. Alpaca. New Zealand Wool.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c11cd7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8c11cd7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/azrahomedecor.com\/index.php\/about-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">kNOW mORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a0750d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a0750d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01b4ab6\" data-id=\"01b4ab6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a15d44e elementor-widget elementor-widget-heading\" data-id=\"a15d44e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MANUFACTURING PROCESS\n\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-411d8c3 elementor-widget elementor-widget-text-editor\" data-id=\"411d8c3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>The Local Craftsmen And Weavers Excelled In Hand-Woven Textile Products For Home Use.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-903343f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"903343f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-47122c3\" data-id=\"47122c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bffb970 elementor-widget elementor-widget-image\" data-id=\"bffb970\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/6-724x1024.jpg\" class=\"attachment-large size-large wp-image-2417\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/6-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/6-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/6-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/6-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/6-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/6.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f0ee21 elementor-widget elementor-widget-heading\" data-id=\"7f0ee21\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Designing Process\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-070d19f\" data-id=\"070d19f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dff3917 elementor-widget elementor-widget-image\" data-id=\"dff3917\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1-3-724x1024.jpg\" class=\"attachment-large size-large wp-image-2412\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1-3-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1-3-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1-3-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1-3-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1-3-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1-3.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e2bf0a elementor-widget elementor-widget-heading\" data-id=\"2e2bf0a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Yarn Dyeing Process\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-abbce54\" data-id=\"abbce54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb25657 elementor-widget elementor-widget-image\" data-id=\"fb25657\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2-3-724x1024.jpg\" class=\"attachment-large size-large wp-image-2413\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2-3-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2-3-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2-3-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2-3-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2-3-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2-3.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79c07d0 elementor-widget elementor-widget-heading\" data-id=\"79c07d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Production Process\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a82346 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a82346\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-847b764\" data-id=\"847b764\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5736159 elementor-widget elementor-widget-image\" data-id=\"5736159\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3-2-724x1024.jpg\" class=\"attachment-large size-large wp-image-2414\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3-2-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3-2-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3-2-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3-2-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3-2-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3-2.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7beecc elementor-widget elementor-widget-heading\" data-id=\"b7beecc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Finishing Process\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ebd6661\" data-id=\"ebd6661\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac48d5e elementor-widget elementor-widget-image\" data-id=\"ac48d5e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/4-1-724x1024.jpg\" class=\"attachment-large size-large wp-image-2415\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/4-1-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/4-1-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/4-1-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/4-1-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/4-1-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/4-1.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e40101 elementor-widget elementor-widget-heading\" data-id=\"4e40101\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quality Control Process\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8f89bed\" data-id=\"8f89bed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3fcb00 elementor-widget elementor-widget-image\" data-id=\"c3fcb00\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/5-1-724x1024.jpg\" class=\"attachment-large size-large wp-image-2416\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/5-1-724x1024.jpg 724w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/5-1-212x300.jpg 212w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/5-1-768x1086.jpg 768w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/5-1-1086x1536.jpg 1086w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/5-1-1448x2048.jpg 1448w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/5-1.jpg 1587w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cb53fa elementor-widget elementor-widget-heading\" data-id=\"9cb53fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Packing Process\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21185e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21185e5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43074ab\" data-id=\"43074ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-376d5a9 elementor-widget elementor-widget-text-editor\" data-id=\"376d5a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"subtitle--text text-primary uppercase my-[5px] mt-0 text-center\">Azra Home Decor<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfea0f4 elementor-widget elementor-widget-heading\" data-id=\"dfea0f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The durability of our carpets<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38a1dcd elementor-widget elementor-widget-text-editor\" data-id=\"38a1dcd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>At Azra Home Decor, our rugs are made in India following ancestral know-how and using quality raw materials. Each rug undergoes 12 meticulous stages of creation, involving numerous skilled craftsmen. These artisans are master dyers, spinners, weavers, and more, each a guarantor of unique techniques and gestures passed down through generations. They spin, dye, weave, tuft, knot, and wash our rugs according to the timeless rules of their art. This perpetuated tradition evolves and modernizes, ensuring the precision and quality that define our rugs at Azra Home Decor.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1905278 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1905278\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d67c73\" data-id=\"8d67c73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4e7808 elementor-widget elementor-widget-heading\" data-id=\"b4e7808\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Weaving Stories, Preserving Traditions, Enhancing Spaces<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cfe3dcd elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfe3dcd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1637c13\" data-id=\"1637c13\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f67602d elementor-widget elementor-widget-image\" data-id=\"f67602d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-5.avif\" class=\"attachment-large size-large wp-image-2688\" alt=\"Handmade\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-5.avif 200w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-5-150x150.avif 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8a8375 elementor-widget elementor-widget-heading\" data-id=\"a8a8375\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Handmade<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-57ae262\" data-id=\"57ae262\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3642fa6 elementor-widget elementor-widget-image\" data-id=\"3642fa6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-4.avif\" class=\"attachment-large size-large wp-image-2687\" alt=\"Promotion of craftsmanship\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-4.avif 200w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-4-150x150.avif 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7c96a3 elementor-widget elementor-widget-heading\" data-id=\"a7c96a3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Promotion of craftsmanship<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0210f49\" data-id=\"0210f49\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a27bb57 elementor-widget elementor-widget-image\" data-id=\"a27bb57\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-3.avif\" class=\"attachment-large size-large wp-image-2686\" alt=\"Natural fibers\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-3.avif 200w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-3-150x150.avif 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-353ef76 elementor-widget elementor-widget-heading\" data-id=\"353ef76\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Natural fibers<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8220ee3\" data-id=\"8220ee3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d36b74 elementor-widget elementor-widget-image\" data-id=\"1d36b74\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-2.avif\" class=\"attachment-large size-large wp-image-2685\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-2.avif 200w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-2-150x150.avif 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8193cf1 elementor-widget elementor-widget-heading\" data-id=\"8193cf1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Guarantee of social values<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6302327\" data-id=\"6302327\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25a8b91 elementor-widget elementor-widget-image\" data-id=\"25a8b91\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-1.avif\" class=\"attachment-large size-large wp-image-2684\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-1.avif 200w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/azra-1-150x150.avif 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88b8927 elementor-widget elementor-widget-heading\" data-id=\"88b8927\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Preservation of the environment<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06afe5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06afe5a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5b1962\" data-id=\"a5b1962\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23a27d0 elementor-widget elementor-widget-text-editor\" data-id=\"23a27d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"subtitle--text text-primary uppercase my-[5px] mt-0 text-center\">Discover<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b49d3e6 elementor-widget elementor-widget-heading\" data-id=\"b49d3e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our projects\n\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74d493c elementor-widget elementor-widget-text-editor\" data-id=\"74d493c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>At Azra Home Decor, we offer professionals a service dedicated to special projects, tailored to the needs of specifiers. Our products meet the requirements of even the most ambitious projects, thanks to the flexibility of manual production. Whether for public construction sites like hotels, offices, and stores, or private spaces such as residences and yachts, we provide products adapted to both the decor and technical constraints. Most of our rugs are custom-made, fully depending on customer choice, ensuring that each piece is unique and perfectly suited to your specific needs.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11d10c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11d10c2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-058b449\" data-id=\"058b449\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85febae elementor-widget elementor-widget-image\" data-id=\"85febae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"540\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1.png\" class=\"attachment-large size-large wp-image-2732\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1.png 360w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/1-200x300.png 200w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c65297e\" data-id=\"c65297e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afe46ac elementor-widget elementor-widget-image\" data-id=\"afe46ac\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"540\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3.png\" class=\"attachment-large size-large wp-image-2734\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3.png 360w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/3-200x300.png 200w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1263673\" data-id=\"1263673\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c321f3 elementor-widget elementor-widget-image\" data-id=\"0c321f3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"540\" src=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2.png\" class=\"attachment-large size-large wp-image-2733\" alt=\"\" srcset=\"https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2.png 360w, https:\/\/azrahomedecor.com\/wp-content\/uploads\/2024\/07\/2-200x300.png 200w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53759ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53759ea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a0b494\" data-id=\"8a0b494\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efbbd70 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"efbbd70\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/azrahomedecor.com\/index.php\/executed-projects\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">sEE mORE eXECUTED projects<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43cce80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43cce80\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f1a0bd8\" data-id=\"f1a0bd8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a762d2 elementor-widget elementor-widget-shortcode\" data-id=\"6a762d2\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><style type=\"text\/css\">.zoom-instagram.feed-2797{font-size:14px!important;padding:1px!important;}.zoom-instagram.feed-2797 .zoom-instagram-widget__items{display:grid!important;grid-template-columns:repeat(3,1fr);}.zoom-instagram.feed-2797 .zoom-instagram-widget__items{gap:5px!important;}<\/style>\n&#8230;<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Discover the Art of Handcrafted EleganceHandmade Masterpieces for Every Corner of Your HomeHand Tufted: Timeless CraftsmanshipCrafted with precision and care, our hand-tufted carpets showcase exquisite detail and durability. Hand Dyeing: Crafting Vibrant TexturesExpertly hand-dyed for vibrant textures and unique patterns. Previous slide Next slide Authentic Rug Crafting Techniques Experience the Elegance of Hand-Tufted, Hand-Knotted, Hand-Loomed, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2381,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2292","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/azrahomedecor.com\/index.php\/wp-json\/wp\/v2\/pages\/2292"}],"collection":[{"href":"https:\/\/azrahomedecor.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/azrahomedecor.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/azrahomedecor.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/azrahomedecor.com\/index.php\/wp-json\/wp\/v2\/comments?post=2292"}],"version-history":[{"count":215,"href":"https:\/\/azrahomedecor.com\/index.php\/wp-json\/wp\/v2\/pages\/2292\/revisions"}],"predecessor-version":[{"id":2834,"href":"https:\/\/azrahomedecor.com\/index.php\/wp-json\/wp\/v2\/pages\/2292\/revisions\/2834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/azrahomedecor.com\/index.php\/wp-json\/wp\/v2\/media\/2381"}],"wp:attachment":[{"href":"https:\/\/azrahomedecor.com\/index.php\/wp-json\/wp\/v2\/media?parent=2292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}